{"id":1713,"date":"2023-06-01T15:14:09","date_gmt":"2023-06-01T13:14:09","guid":{"rendered":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/?p=1713"},"modified":"2023-06-01T15:15:38","modified_gmt":"2023-06-01T13:15:38","slug":"balkonsolaranlagen-im-moeckernkiez","status":"publish","type":"post","link":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2023\/06\/01\/balkonsolaranlagen-im-moeckernkiez\/","title":{"rendered":"Balkonsolaranlagen im M\u00f6ckernkiez"},"content":{"rendered":"\n<p>Von Natalie, Balkonsolar AG<\/p>\n\n\n\n<p>Energiewende als MieterInnen vorantreiben, indem man durch Solarmodule am eigenen Balkon Strom produziert und diesen direkt selber nutzt. Eine M\u00f6glichkeit, die das Interesse vieler GenossInnen geweckt hat. Bef\u00f6rdert wurde dies sicherlich auch durch das F\u00f6rderprogramm des Berliner Senats, der seit Anfang des Jahres Balkonsolaranlagen mit bis zu 500 Euro unterst\u00fctzt. Auch Stand Mai ist dieser F\u00f6rdertopf offenbar noch nicht ausgesch\u00f6pft.<\/p>\n\n\n\n<p>Seit den ersten Interessensbekundungen an Balkonsolaranlagen im M\u00f6ckernkiez im Sommer vergangenen Jahres hat sich eine Balkonsolar AG im M\u00f6ckernkiez gegr\u00fcndet, die in Abstimmung mit dem Vorstand der Genossenschaft Angebote f\u00fcr die fachgerechte Anbringung von Balkon-Solarmodulen im M\u00f6ckernkiez unter Wahrung eines einheitlichen Erscheinungsbildes eingeholt hat. Die Umsetzung findet durch die Firma Sonnenrepublik sowie deren Installationsfirma Oloid statt.<\/p>\n\n\n\n<p>Der ganze Prozess hat sich dabei als etwas langwieriger als erwartet herausgestellt, dies liegt u.a.  an den noch immer bestehenden administrativen und technischen Herausforderungen, die nach der derzeitig noch geltenden Gesetzeslage zu beachten sind. Beispielhaft genannt sei u.a. die Reihenfolge der einzelnen Schritte (z.B. erst F\u00f6rderantrag stellen, falls gew\u00fcnscht, danach Beauftragung bzw. Kauf von Modulen), die Kl\u00e4rung von Messkonzepten, weitere Meldeerfordernisse und nicht zuletzt auch die verschiedenen Bauformen von Balkonen im M\u00f6ckernkiez, die ein jeweils angepasstes Angebot im Hinblick auf Modulgr\u00f6\u00dfe und Befestigungsart erfordern.<\/p>\n\n\n\n<p>Dazu haben wir (ohne Anspruch auf Vollst\u00e4ndigkeit) einen Leitfaden f\u00fcr Balkonsolaranlagen im M\u00f6ckernkiez erstellt, der <a href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2023\/06\/Auftragsformular_gesamt_Balkonsolar_Moeckernkiez.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> heruntergeladen werden kann.<\/p>\n\n\n\n<p>Nachdem eine gro\u00dfe online-Informationsveranstaltung am 25. April 2023 stattgefunden hat, konnte es dann mit der Beauftragung losgehen, die im Mai 2023 zun\u00e4chst bei der Gesch\u00e4ftsstelle gemeinsam mit den Antr\u00e4gen auf Mietereinbau abgegeben wurden und von dort gesammelt an die Firma Sonnenrepublik weitergegeben wurden.<\/p>\n\n\n\n<p>Stand Mai 2023 wurden 40 Balkonsolaranlagen im M\u00f6ckernkiez beauftragt, die ersten Rechnungen wurden bereits verschickt und mit der Herstellung der speziellen Halterungen f\u00fcr unsere Balkone wurde bereits begonnen. Voraussichtlich Anfang Juli werden dann in einer gesammelten Aktion die<br>Balkonsolaranlagen angebracht und produzieren ab dann dezentral Strom. <br>Die Terminabstimmung, sobald alle Komponenten fertig sind, wird sicherlich nochmal einen gewissen organisatorischen Abstimmungsaufwand erfordern, aber auch das werden wir hier im M\u00f6ckernkiez hinkriegen!<\/p>\n\n\n\n<p>Auch wenn die Sammelbestellungen schon abgeschlossen sind, keine Sorge, alle die auch eine Balkonsolaranlage wollen und es bis jetzt nicht geschafft haben, sich darum zu k\u00fcmmern oder erstmal abwarten wollten, k\u00f6nnen diese nat\u00fcrlich immernoch bei Sonnenrepublik beauftragen.<\/p>\n\n\n\n<p>Angesicht der diversen Gesetzesvorhaben zum Abbau der administrativen H\u00fcrden bei Balkonsolaranlagen d\u00fcrfte es zuk\u00fcnftig sogar noch die eine oder andere Erleichterung geben. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Natalie, Balkonsolar AG Energiewende als MieterInnen vorantreiben, indem man durch Solarmodule am eigenen Balkon Strom produziert und diesen direkt selber nutzt. Eine M\u00f6glichkeit, die das Interesse vieler GenossInnen geweckt hat. Bef\u00f6rdert wurde dies sicherlich auch durch das F\u00f6rderprogramm des Berliner Senats, der seit Anfang des Jahres Balkonsolaranlagen mit bis zu 500 Euro unterst\u00fctzt. Auch &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Balkonsolaranlagen im M\u00f6ckernkiez\" class=\"read-more button\" href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2023\/06\/01\/balkonsolaranlagen-im-moeckernkiez\/#more-1713\" aria-label=\"Mehr Informationen \u00fcber Balkonsolaranlagen im M\u00f6ckernkiez\">Beitrag lesen<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1713","post","type-post","status-publish","format-standard","hentry","category-klimaschutz"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:00:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/1713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/comments?post=1713"}],"version-history":[{"count":2,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/1713\/revisions"}],"predecessor-version":[{"id":1716,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/1713\/revisions\/1716"}],"wp:attachment":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media?parent=1713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/categories?post=1713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/tags?post=1713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}