{"id":4586,"date":"2024-07-09T20:17:20","date_gmt":"2024-07-09T18:17:20","guid":{"rendered":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/?p=4586"},"modified":"2024-07-09T20:48:07","modified_gmt":"2024-07-09T18:48:07","slug":"die-moeckernkiez-rikscha-ist-da","status":"publish","type":"post","link":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2024\/07\/09\/die-moeckernkiez-rikscha-ist-da\/","title":{"rendered":"Die M\u00f6ckernkiez-Rikscha ist da!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Im M\u00f6ckernkiez gibt es jetzt eine Rikscha, genannt &#8218;M\u00f6ckscha&#8216;, die ausgeliehen werden kann (<a href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/07\/Flyer_Moeck_Rikscha_6.pdf\">Flyer<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zur Erh\u00f6hung der Mobilit\u00e4t der im M\u00f6ckernkiez wohnenden Menschen mit Behinderung sowie der mobilit\u00e4tseingeschr\u00e4nkten BewohnerInnen des M\u00f6ckernkiez, hat der M\u00f6ckernKiez e.V. \u00fcber F\u00f6rdermittel der &#8218;Aktion Mensch&#8216; eine moderne E(lektrische)-Rikscha angeschafft. Dies wurde erm\u00f6glicht durch die enge Kooperation des M\u00f6ckernKiez e. V. mit dem AJB e.V.. Dieser betreut im M\u00f6ckernkiez zwei Jugend-WGs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit der Rikscha kann die Teilhabe am Leben sp\u00fcrbar erh\u00f6ht werden. Mit einem solchen Fahrzeug k\u00f6nnen nicht nur die n\u00e4heren Strecken rund um den M\u00f6ckernkiez gemeistert werden, mehr noch, es k\u00f6nnen ausgedehntere Fahrradausfl\u00fcge in die Stadt und die n\u00e4here, umliegende Natur unternommen werden (Reichweite: 20 &#8211; 60 km, je nach Trainingszustand des\/der Pilotin\/en).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Menschen mit Behinderung oder sonstigen Einschr\u00e4nkungen, die nicht in der Lage sind selbst Rad zu fahren, gibt es die Rikscha. Diese darf allerdings ausschliesslich von eingewiesenen PilotInnen gefahren werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/07\/Einweisung_Rikscha_2-1.pdf\">Schulung <\/a>und Training zum Rikscha-Piloten d\u00fcrfen selbstverst\u00e4ndlich alle absolvieren die Lust darauf haben.<br>Wer erfolgreich das Training abschlie\u00dft, kann dann eine Rikscha mit (Fahr-)G\u00e4sten fahren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Fahrrad-Rikscha k\u00f6nnen zwei Fahrg\u00e4ste mitgenommen werden. So sind gesellige Ausfahrten m\u00f6glich und die Fahrg\u00e4ste k\u00f6nnen sich wunderbar untereinander, gerne auch mit dem Fahrer austauschen. Die Fahrg\u00e4ste sind angeschnallt und so vor dem Rauskippen aus der Rikscha gesichert. Durch die elektrische Unterst\u00fctzung kommen die Rikschas auch bei voller Last (2 Personen mit Gep\u00e4ck), auf Wunsch und wenn es die Verh\u00e4ltnisse zulassen, z\u00fcgig voran.<br>Die Fahrrad-Rikscha ist von dem holl\u00e4ndischen Unternehmen Van Raam und die aktuell wohl sicherste und f\u00fcr die Passagiere komfortabelste Rikscha auf dem Markt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Verein sucht immer radbegeisterte freiwillige <a href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/07\/Info-fuer-RikschafahrerInnen.pdf\">Rikscha-FahrerInnen<\/a>, die gerne mit dem Fahrzeug Ausfahrten unternehmen wollen. Es macht Spa\u00df mit der elektrischen Rikscha zu fahren \u2013 und es macht Spa\u00df gefahren zu werden. Bei Interesse reicht eine kurze Email an rikscha@moeckernkiez-ev.de, dann vereinbaren wir einen Schulungstermin bzw. im Falle einer vorliegenden <a href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/07\/Einweisung_Rikscha_2-1.pdf\">Einweisung<\/a> kann reserviert werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der kostenlose Verleih der Rikscha wird \u00fcber den M\u00f6ckernkiez-Verein organisiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wer sich gerne fahren lassen will, kann sich \u00fcber den <a href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/rikscha\/#rikschakalender\">Rikscha-Kalender<\/a> informieren an welchen Tagen die Rikscha noch frei ist. Um die Rikscha anzufragen brauchen wir einige Angaben. F\u00fcllt dazu bitte unser Anfrageformular aus. Steht an dem gew\u00fcnschten Tag auch eine geschulte PilotIn zur Verf\u00fcgung, steht dem Ausflug nichts mehr im Wege.<br>Bei allen Fragen direkt an rikscha@moeckernkiez-ev.de wenden!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im M\u00f6ckernkiez gibt es jetzt eine Rikscha, genannt &#8218;M\u00f6ckscha&#8216;, die ausgeliehen werden kann (Flyer). Zur Erh\u00f6hung der Mobilit\u00e4t der im M\u00f6ckernkiez wohnenden Menschen mit Behinderung sowie der mobilit\u00e4tseingeschr\u00e4nkten BewohnerInnen des M\u00f6ckernkiez, hat der M\u00f6ckernKiez e.V. \u00fcber F\u00f6rdermittel der &#8218;Aktion Mensch&#8216; eine moderne E(lektrische)-Rikscha angeschafft. Dies wurde erm\u00f6glicht durch die enge Kooperation des M\u00f6ckernKiez e. V. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Die M\u00f6ckernkiez-Rikscha ist da!\" class=\"read-more button\" href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2024\/07\/09\/die-moeckernkiez-rikscha-ist-da\/#more-4586\" aria-label=\"Mehr Informationen \u00fcber Die M\u00f6ckernkiez-Rikscha ist da!\">Beitrag lesen<\/a><\/p>\n","protected":false},"author":6,"featured_media":4302,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,91],"tags":[],"class_list":["post-4586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-familien"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 16:59:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/4586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/comments?post=4586"}],"version-history":[{"count":4,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/4586\/revisions"}],"predecessor-version":[{"id":4594,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/4586\/revisions\/4594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media\/4302"}],"wp:attachment":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media?parent=4586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/categories?post=4586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/tags?post=4586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}