{"id":5165,"date":"2024-09-10T16:40:43","date_gmt":"2024-09-10T14:40:43","guid":{"rendered":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/?p=5165"},"modified":"2024-09-23T13:05:39","modified_gmt":"2024-09-23T11:05:39","slug":"rollende-demo-vor-dem-kanzleramt","status":"publish","type":"post","link":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2024\/09\/10\/rollende-demo-vor-dem-kanzleramt\/","title":{"rendered":"&#8222;Rollende Demo&#8220; vor dem Kanzleramt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die &#8222;Rollende Demo&#8220; f\u00fcr &#8222;Barrierefreiheit jetzt&#8220; hielt ihre Kundgebung am 10.9.24 vor dem Kanzleramt ab. Leider ohne Signal von Kanzler Scholz, aber das war ja auch nicht zu erwarten. \u00dcber 200 Aktive f\u00fcr Barrierefreiheit in Deutschland (und Hawaii!) versammelten sich beim Brandenburger Tor und bewegten sich in einem (Rollstuhl-) Korso zum Kanzleramt. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit dabei die &#8222;Freiheitsstatue&#8220; f\u00fcr Barrierefreiheit, eine Freiheitsstatue im Rollstuhl. Die h\u00e4tte auch gut zu dem am Abend stattfindenden Empfang des Bundesbeauftragten f\u00fcr die Belange von Menschen mit Behinderung, Herr J\u00fcrgen Dusel, gepasst. Da ist n\u00e4mlich auch Kanzler Scholz zu Gast und h\u00e4tte damit zum zweiten Mal an diesem Tag die Gelegenheit sich mit den ganzen politischen Vers\u00e4umnissen zur Barrierefreiheit in Deutschland zu besch\u00e4ftigen. Sch\u00f6ne Worte wird es bestimmt geben und, wieder, Versprechungen, Versprechungen die ja schon lange im Koalitionsvertrag stehen und dort offenbar einen guten Standort gefunden haben um gegen\u00fcber den Problemen der Weltpolitik nicht Wirklichkeit werden zu m\u00fcssen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Stimmung auf der Rollenden Demo war trotzdem voller Engagement und Hoffnung, auch Berliner Inklusions-Aktivisten sind gesehen worden, stark vertreten der ABSV, das Wetter hat mitgespielt, kein Regen, am Ende war es eine eindrucksvolle &#8222;Rollende Demo&#8220;, so was kann ruhig \u00f6fters im Jahr stattfinden, in der Aktivit\u00e4t nachlassen ist keine Option.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5177\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor1-1024x768.jpg\" alt=\"\" class=\"wp-image-5177\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor1-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor1-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor1-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor1-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor1-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor1-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5199\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor2-1024x768.jpg\" alt=\"\" class=\"wp-image-5199\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor2-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor2-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor2-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor2-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor2-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor2-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5197\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor3-1024x768.jpg\" alt=\"\" class=\"wp-image-5197\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor3-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor3-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor3-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor3-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor3-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor3-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5191\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor4-768x1024.jpg\" alt=\"\" class=\"wp-image-5191\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor4-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor4-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor4-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor4-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor4-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor4-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5185\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor5-768x1024.jpg\" alt=\"\" class=\"wp-image-5185\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor5-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor5-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor5-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor5-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor5-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor5-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5188\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor6-768x1024.jpg\" alt=\"\" class=\"wp-image-5188\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor6-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor6-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor6-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor6-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor6-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor6-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5183\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor7-1024x768.jpg\" alt=\"\" class=\"wp-image-5183\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor7-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor7-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor7-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor7-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor7-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor7-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5176\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor8-768x1024.jpg\" alt=\"\" class=\"wp-image-5176\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor8-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor8-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor8-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor8-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor8-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor8-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5198\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor9-768x1024.jpg\" alt=\"\" class=\"wp-image-5198\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor9-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor9-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor9-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor9-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor9-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor9-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5187\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor10-1024x768.jpg\" alt=\"\" class=\"wp-image-5187\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor10-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor10-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor10-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor10-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor10-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor10-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5196\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor11-768x1024.jpg\" alt=\"\" class=\"wp-image-5196\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor11-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor11-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor11-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor11-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor11-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor11-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5181\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor12-1024x768.jpg\" alt=\"\" class=\"wp-image-5181\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor12-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor12-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor12-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor12-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor12-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor12-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5178\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor13-768x1024.jpg\" alt=\"\" class=\"wp-image-5178\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor13-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor13-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor13-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor13-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor13-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor13-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5175\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor14-1024x768.jpg\" alt=\"\" class=\"wp-image-5175\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor14-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor14-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor14-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor14-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor14-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/BrTor14-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5180\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA1-1024x768.jpg\" alt=\"\" class=\"wp-image-5180\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA1-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA1-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA1-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA1-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA1-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA1-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5179\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA2-768x1024.jpg\" alt=\"\" class=\"wp-image-5179\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA2-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA2-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA2-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA2-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA2-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA2-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5184\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA3-1024x768.jpg\" alt=\"\" class=\"wp-image-5184\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA3-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA3-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA3-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA3-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA3-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA3-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5193\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA4-768x1024.jpg\" alt=\"\" class=\"wp-image-5193\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA4-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA4-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA4-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA4-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA4-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/KA4-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5182\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug1-768x1024.jpg\" alt=\"\" class=\"wp-image-5182\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug1-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug1-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug1-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug1-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug1-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5189\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug2-1024x768.jpg\" alt=\"\" class=\"wp-image-5189\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug2-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug2-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug2-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug2-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug2-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug2-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5186\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug3-1024x768.jpg\" alt=\"\" class=\"wp-image-5186\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug3-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug3-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug3-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug3-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug3-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug3-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5192\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug4-1024x768.jpg\" alt=\"\" class=\"wp-image-5192\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug4-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug4-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug4-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug4-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug4-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug4-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5195\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug5-768x1024.jpg\" alt=\"\" class=\"wp-image-5195\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug5-768x1024.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug5-225x300.jpg 225w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug5-1152x1536.jpg 1152w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug5-1536x2048.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug5-1320x1760.jpg 1320w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug5-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5190\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug6-1024x768.jpg\" alt=\"\" class=\"wp-image-5190\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug6-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug6-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug6-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug6-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug6-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug6-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5194\" src=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug7-1024x768.jpg\" alt=\"\" class=\"wp-image-5194\" srcset=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug7-1024x768.jpg 1024w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug7-300x225.jpg 300w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug7-768x576.jpg 768w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug7-1536x1152.jpg 1536w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug7-2048x1536.jpg 2048w, https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-content\/uploads\/2024\/09\/Zug7-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">kb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die &#8222;Rollende Demo&#8220; f\u00fcr &#8222;Barrierefreiheit jetzt&#8220; hielt ihre Kundgebung am 10.9.24 vor dem Kanzleramt ab. Leider ohne Signal von Kanzler Scholz, aber das war ja auch nicht zu erwarten. \u00dcber 200 Aktive f\u00fcr Barrierefreiheit in Deutschland (und Hawaii!) versammelten sich beim Brandenburger Tor und bewegten sich in einem (Rollstuhl-) Korso zum Kanzleramt. Mit dabei die &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"&#8222;Rollende Demo&#8220; vor dem Kanzleramt\" class=\"read-more button\" href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2024\/09\/10\/rollende-demo-vor-dem-kanzleramt\/#more-5165\" aria-label=\"Mehr Informationen \u00fcber &#8222;Rollende Demo&#8220; vor dem Kanzleramt\">Beitrag lesen<\/a><\/p>\n","protected":false},"author":6,"featured_media":5172,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,86,64,4],"tags":[],"class_list":["post-5165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-archiv","category-politik","category-veranstaltung"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:49:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/5165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/comments?post=5165"}],"version-history":[{"count":7,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/5165\/revisions"}],"predecessor-version":[{"id":5200,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/5165\/revisions\/5200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media\/5172"}],"wp:attachment":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media?parent=5165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/categories?post=5165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/tags?post=5165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}