{"id":590,"date":"2023-01-01T13:24:32","date_gmt":"2023-01-01T12:24:32","guid":{"rendered":"http:\/\/localhost:8888\/?p=590"},"modified":"2023-07-02T22:37:14","modified_gmt":"2023-07-02T20:37:14","slug":"ag-nachbarschaftshilfe","status":"publish","type":"post","link":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2023\/01\/01\/ag-nachbarschaftshilfe\/","title":{"rendered":"AG Nachbarschaftshilfe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pflegebedarf und nachbarschaftliche Unterst\u00fctzung&nbsp;<br>Am 25. Januar um 17 Uhr kommt&nbsp;Tina&nbsp;Westphal vom&nbsp;Pflegest\u00fctzpunkt Friedrichshain\/Kreuzberg&nbsp;in der Prinzenstra\u00dfe in den M\u00f6ckernkiez.&nbsp; Der Pflegest\u00fctzpunkt ber\u00e4t, wenn Pflegebedarf entsteht: Wo und wie stellt man einen Antrag bei der Pflegekasse? Welche M\u00f6glichkeiten gibt es, wenn ich allein nicht mehr klar komme? Wie sieht es aus mit Pflegediensten? Und: Was kann nachbarschaftliche Hilfe leisten, welches sind hier die M\u00f6glichkeiten aber auch Grenzen?&nbsp; Frau Westphal informiert zu Fragen rund um Pflege und Alter sowie zur Arbeit des Pflegest\u00fctzpunktes. Sie hat jahrelange Erfahrung und m\u00f6chte gerne mit uns ins Gespr\u00e4ch kommen. <strong><br>Mittwoch, 25. Januar, 17 &#8211; 18:30 Uhr, Forum&nbsp;<\/strong> <em><br>Text: Karin Doehne; Foto: CD<\/em> .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pflegebedarf und nachbarschaftliche Unterst\u00fctzung&nbsp;Am 25. Januar um 17 Uhr kommt&nbsp;Tina&nbsp;Westphal vom&nbsp;Pflegest\u00fctzpunkt Friedrichshain\/Kreuzberg&nbsp;in der Prinzenstra\u00dfe in den M\u00f6ckernkiez.&nbsp; Der Pflegest\u00fctzpunkt ber\u00e4t, wenn Pflegebedarf entsteht: Wo und wie stellt man einen Antrag bei der Pflegekasse? Welche M\u00f6glichkeiten gibt es, wenn ich allein nicht mehr klar komme? Wie sieht es aus mit Pflegediensten? Und: Was kann nachbarschaftliche Hilfe &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"AG Nachbarschaftshilfe\" class=\"read-more button\" href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2023\/01\/01\/ag-nachbarschaftshilfe\/#more-590\" aria-label=\"Mehr Informationen \u00fcber AG Nachbarschaftshilfe\">Beitrag lesen<\/a><\/p>\n","protected":false},"author":4,"featured_media":591,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86,66,4],"tags":[],"class_list":["post-590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv","category-nachbarschaftshilfe","category-veranstaltung"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:35:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":1,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"predecessor-version":[{"id":1902,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/590\/revisions\/1902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media\/591"}],"wp:attachment":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}