{"id":6829,"date":"2025-04-10T17:22:20","date_gmt":"2025-04-10T15:22:20","guid":{"rendered":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/?p=6829"},"modified":"2025-04-10T17:22:20","modified_gmt":"2025-04-10T15:22:20","slug":"neues-kiezprojekt-eigen-werk","status":"publish","type":"post","link":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2025\/04\/10\/neues-kiezprojekt-eigen-werk\/","title":{"rendered":"Neues Kiezprojekt: Eigen Werk"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Eigen Werk M\u00f6ckernkiez \u2013 neue Projektvorstellung am Mittwoch, 23. April im M\u00f6ca<br>Wir, Susa aus G10 und Erika aus G1 Nord, m\u00f6chten euch f\u00fcr folgende Idee begeistern und laden euch ein, Teil davon zu werden:<br>In unserer Nachbarschaft gibt es viele Selbstst\u00e4ndige mit den unterschiedlichsten Berufen \u2013 und Menschen mit vielf\u00e4ltigen F\u00e4higkeiten, die gelegentlich gegen ein kleines Dankesch\u00f6n etwas anbieten m\u00f6chten. Mit dem EigenWerk M\u00f6ckernkiez machen wir diese F\u00fclle in einer Online-Liste sichtbar. Dieses Angebot ist f\u00fcr Anbieter und Nutzer kostenfrei.<br>Ob Coaching, Nachhilfe, Babysitting oder Hilfe bei der Renovierung \u2013 viele von uns bieten etwas an, von dem andere bisher noch gar nichts wissen.<br>Hast du ein bestehendes Business oder ein Talent, das du Nachbarn gerne zug\u00e4nglich machen m\u00f6chtest? Vielleicht wird genau das von Menschen im M\u00f6ckernkiez gesucht, was du mit Freude machst und hier anbietest.<br>Weitere Informationen unter www.eigenwerk.info<br>Du bist herzlich eingeladen zum ersten Kennenlern- und Austauschtreffen am Mittwoch, den 23. April von18:30 bis 20:30 Uhr im M\u00f6ca.<br>Wir freuen uns auf Dich!<br>Herzliche Gr\u00fc\u00dfe<br>Susa &amp; Erika<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eigen Werk M\u00f6ckernkiez \u2013 neue Projektvorstellung am Mittwoch, 23. April im M\u00f6caWir, Susa aus G10 und Erika aus G1 Nord, m\u00f6chten euch f\u00fcr folgende Idee begeistern und laden euch ein, Teil davon zu werden:In unserer Nachbarschaft gibt es viele Selbstst\u00e4ndige mit den unterschiedlichsten Berufen \u2013 und Menschen mit vielf\u00e4ltigen F\u00e4higkeiten, die gelegentlich gegen ein kleines &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Neues Kiezprojekt: Eigen Werk\" class=\"read-more button\" href=\"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/2025\/04\/10\/neues-kiezprojekt-eigen-werk\/#more-6829\" aria-label=\"Mehr Informationen \u00fcber Neues Kiezprojekt: Eigen Werk\">Beitrag lesen<\/a><\/p>\n","protected":false},"author":6,"featured_media":6828,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 23:27:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/6829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/comments?post=6829"}],"version-history":[{"count":1,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/6829\/revisions"}],"predecessor-version":[{"id":6830,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/posts\/6829\/revisions\/6830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media\/6828"}],"wp:attachment":[{"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/media?parent=6829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/categories?post=6829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moeckernkiez-ev.de\/Wordpress_MK\/wp-json\/wp\/v2\/tags?post=6829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}